{"id":4425,"date":"2019-09-14T01:49:37","date_gmt":"2019-09-13T22:49:37","guid":{"rendered":"https:\/\/karklessodyba.lt\/?page_id=4425"},"modified":"2026-05-05T12:34:46","modified_gmt":"2026-05-05T09:34:46","slug":"kainos","status":"publish","type":"page","link":"https:\/\/karklessodyba.lt\/en\/prices\/","title":{"rendered":"Prices"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4425\" class=\"elementor elementor-4425\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad21f87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad21f87\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9273641\" data-id=\"9273641\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68662b4 elementor-widget elementor-widget-thim-icon-box\" data-id=\"68662b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"inner-box auto-hidden\"><div  class=\"wrapper-box-icon text-center   wrapper-line-heading\" ><div class=\"smicon-box iconbox-top\"><div class=\"content-inner\" ><div class=\"sc-heading article_heading\"><h3 class = \"heading__primary\" >Karkle Homestead (Karkle Beach Apartments)<br>\n2025 - 2026 prices:<\/h3><span class=\"line-heading\"><span><\/span><\/span><\/div><div class=\"desc-icon-box\"><div style=\"color: #444444;font-weight: normal;\"><div id=\"tablepress-1-scroll-wrapper\" class=\"tablepress-scroll-wrapper\">\n\n<table id=\"tablepress-1\" class=\"tablepress tablepress-id-1 tablepress-responsive\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">until 05.22<\/td><td class=\"column-3\">05.22-06.12<\/td><td class=\"column-4\">06.12-06.19<\/td><td class=\"column-5\">06.19-07.01<\/td><td class=\"column-6\">07.01-08.23<\/td><td class=\"column-7\">08.23-08.30<\/td><td class=\"column-8\">08.30-09.20<\/td><td class=\"column-9\">from 09.20<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">EUR<\/td><td class=\"column-3\">EUR<\/td><td class=\"column-4\">EUR<\/td><td class=\"column-5\">EUR<\/td><td class=\"column-6\">EUR<\/td><td class=\"column-7\">EUR<\/td><td class=\"column-8\">EUR<\/td><td class=\"column-9\">EUR<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Double<\/td><td class=\"column-2\">35<\/td><td class=\"column-3\">40<\/td><td class=\"column-4\">45<\/td><td class=\"column-5\">55<\/td><td class=\"column-6\">75<\/td><td class=\"column-7\">65<\/td><td class=\"column-8\">40<\/td><td class=\"column-9\">35<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Triple<\/td><td class=\"column-2\">40<\/td><td class=\"column-3\">45<\/td><td class=\"column-4\">50<\/td><td class=\"column-5\">60<\/td><td class=\"column-6\">85<\/td><td class=\"column-7\">70<\/td><td class=\"column-8\">45<\/td><td class=\"column-9\">40<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Quadruple<\/td><td class=\"column-2\">45<\/td><td class=\"column-3\">50<\/td><td class=\"column-4\">55<\/td><td class=\"column-5\">70<\/td><td class=\"column-6\">100<\/td><td class=\"column-7\">80<\/td><td class=\"column-8\">50<\/td><td class=\"column-9\">45<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">The Pentecostal<\/td><td class=\"column-2\">50<\/td><td class=\"column-3\">55<\/td><td class=\"column-4\">60<\/td><td class=\"column-5\">80<\/td><td class=\"column-6\">105<\/td><td class=\"column-7\">90<\/td><td class=\"column-8\">55<\/td><td class=\"column-9\">50<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Double room with sea view<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">For two<\/td><td class=\"column-2\">39<\/td><td class=\"column-3\">44<\/td><td class=\"column-4\">49<\/td><td class=\"column-5\">59<\/td><td class=\"column-6\">79<\/td><td class=\"column-7\">69<\/td><td class=\"column-8\">44<\/td><td class=\"column-9\">39<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">2-room with sea view (2nd floor) or 3-room, over 2 floors (2nd, 3rd floor)<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">For two<\/td><td class=\"column-2\">48<\/td><td class=\"column-3\">52<\/td><td class=\"column-4\">60<\/td><td class=\"column-5\">90<\/td><td class=\"column-6\">110<\/td><td class=\"column-7\">96<\/td><td class=\"column-8\">56<\/td><td class=\"column-9\">50<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">For three<\/td><td class=\"column-2\">50<\/td><td class=\"column-3\">54<\/td><td class=\"column-4\">62<\/td><td class=\"column-5\">92<\/td><td class=\"column-6\">112<\/td><td class=\"column-7\">98<\/td><td class=\"column-8\">58<\/td><td class=\"column-9\">52<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">For four<\/td><td class=\"column-2\">52<\/td><td class=\"column-3\">56<\/td><td class=\"column-4\">64<\/td><td class=\"column-5\">94<\/td><td class=\"column-6\">114<\/td><td class=\"column-7\">100<\/td><td class=\"column-8\">60<\/td><td class=\"column-9\">54<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">For five<\/td><td class=\"column-2\">54<\/td><td class=\"column-3\">62<\/td><td class=\"column-4\">68<\/td><td class=\"column-5\">96<\/td><td class=\"column-6\">116<\/td><td class=\"column-7\">102<\/td><td class=\"column-8\">62<\/td><td class=\"column-9\">56<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<\/div><!-- #tablepress-1 from cache --><\/div><\/div><\/div><\/div><!--end smicon-box--><\/div><\/div><style>\n\t.smicon-read:hover{\n\t\tcolor: !important;\n\t\tbackground: !important;\n\t}\n\t.smicon-box .boxes-icon:hover{\n\t\tcolor: !important;\n\t\tborder-color: !important;\n\t\tbackground-color:  !important;\n\t}\n\t.smicon-box .boxes-icon:hover .icon i{\n\t\tcolor: !important;\n\t}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40ebb5b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40ebb5b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-572804a\" data-id=\"572804a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0efc088 elementor-widget elementor-widget-thim-icon-box\" data-id=\"0efc088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"inner-box auto-hidden\"><div  class=\"wrapper-box-icon text-center\" ><div class=\"smicon-box iconbox-top\"><div class=\"content-inner\" ><div class=\"desc-icon-box\"><div style=\"color: #444444;font-weight: normal;\"><ul style=\"list-style-type:circle\">\n\t<li>In summer, higher rates than those shown in the price table may apply for bookings of less than 4 nights.<\/li>\n\t<li>The sauna and hot tub are closed from May to September.<\/li>\n\t<li>Pets are welcome. One pet - EUR 10 per night.<\/li>\n\t<li>Check-in is from 15.00 to 23.00.<\/li>\n\t<li>Check-out time is 12.00 (unless another time is agreed in advance).<\/li>\n<\/ul><\/div><\/div><\/div><\/div><!--end smicon-box--><\/div><\/div><style>\n\t.smicon-read:hover{\n\t\tcolor: !important;\n\t\tbackground: !important;\n\t}\n\t.smicon-box .boxes-icon:hover{\n\t\tcolor: !important;\n\t\tborder-color: !important;\n\t\tbackground-color:  !important;\n\t}\n\t.smicon-box .boxes-icon:hover .icon i{\n\t\tcolor: !important;\n\t}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48a7c54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48a7c54\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7cba65e\" data-id=\"7cba65e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96a5548 elementor-widget elementor-widget-thim-icon-box\" data-id=\"96a5548\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"inner-box auto-hidden\"><div  class=\"wrapper-box-icon text-center   wrapper-line-heading\" ><div class=\"smicon-box iconbox-top\"><div class=\"content-inner\" ><div class=\"sc-heading article_heading\"><h3 class = \"heading__primary\" >Apartment amenities:<\/h3><span class=\"line-heading\"><span><\/span><\/span><\/div><div class=\"desc-icon-box\"><div style=\"color: #444444;font-weight: normal;\"><ul style=\"list-style-type:circle\"><li>Private kitchenette: hob (oven in apartment), microwave, electric kettle, fridge, kitchenware;<li>Shower, washing machine, toilet, towels, hairdryer, toilet paper;<li>Wardrobe, TV with Netflix, satellite TV;<li>Underfloor heating;<li>Outdoor furniture;<li>Wireless internet.<\/ul><\/div><\/div><\/div><\/div><!--end smicon-box--><\/div><\/div><style>\n\t.smicon-read:hover{\n\t\tcolor: !important;\n\t\tbackground: !important;\n\t}\n\t.smicon-box .boxes-icon:hover{\n\t\tcolor: !important;\n\t\tborder-color: !important;\n\t\tbackground-color:  !important;\n\t}\n\t.smicon-box .boxes-icon:hover .icon i{\n\t\tcolor: !important;\n\t}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10c3fa7 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10c3fa7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30691af\" data-id=\"30691af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8d17a0 elementor-widget elementor-widget-thim-icon-box\" data-id=\"f8d17a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"inner-box auto-hidden\"><div  class=\"wrapper-box-icon text-center   wrapper-line-heading\" ><div class=\"smicon-box iconbox-top\"><div class=\"content-inner\" ><div class=\"sc-heading article_heading\"><h3 class = \"heading__primary\" >Farmhouse rental prices:<\/h3><span class=\"line-heading\"><span><\/span><\/span><\/div><div class=\"desc-icon-box\"><div style=\"color: #444444;font-weight: normal;\"><ul style=\"list-style-type: circle;\"> <li><strong>Farmhouse with hall and rooms for up to 35 people, without meals<\/strong> - price negotiable.<\/li> <li><strong>Farmhouse with hall and catering for up to 35 people, with meals<\/strong> - price negotiable.<\/li><\/ul>In the off-season, we invite you to celebrate holidays, organise seminars and trainings. Rooms with all amenities. We recommend to book the homestead without unauthorised persons with catering (hall, gala dinner, modern rooms, breakfast, sauna, hot tub). Other rental, (non)catering options available.<\/div><\/div><\/div><\/div><!--end smicon-box--><\/div><\/div><style>\n\t.smicon-read:hover{\n\t\tcolor: !important;\n\t\tbackground: !important;\n\t}\n\t.smicon-box .boxes-icon:hover{\n\t\tcolor: !important;\n\t\tborder-color: !important;\n\t\tbackground-color:  !important;\n\t}\n\t.smicon-box .boxes-icon:hover .icon i{\n\t\tcolor: !important;\n\t}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Karkle Homestead (Karkle Beach Apartments)<br \/>\n2025 - 2026 prices:<\/p>\n<p>\n\t.smicon-read:hover{<br \/>\n\t\tcolour: !important;<br \/>\n\t\tbackground: !important;<br \/>\n\t}<br \/>\n\t.smicon-box .boxes-icon:hover{<br \/>\n\t\tcolour: !important;<br \/>\n\t\tborder-color: !important;<br \/>\n\t\tbackground-color: !important;<br \/>\n\t}<br \/>\n\t.smicon-box .boxes-icon:hover .icon i{<br \/>\n\t\tcolour: !important;<br \/>\n\t}<\/p>\n<p>\nIn summer, higher rates than those shown in the price table may apply for bookings of less than 4 nights.<br \n<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yst_prominent_words":[],"class_list":["post-4425","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/karklessodyba.lt\/en\/wp-json\/wp\/v2\/pages\/4425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karklessodyba.lt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/karklessodyba.lt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/karklessodyba.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/karklessodyba.lt\/en\/wp-json\/wp\/v2\/comments?post=4425"}],"version-history":[{"count":198,"href":"https:\/\/karklessodyba.lt\/en\/wp-json\/wp\/v2\/pages\/4425\/revisions"}],"predecessor-version":[{"id":5717,"href":"https:\/\/karklessodyba.lt\/en\/wp-json\/wp\/v2\/pages\/4425\/revisions\/5717"}],"wp:attachment":[{"href":"https:\/\/karklessodyba.lt\/en\/wp-json\/wp\/v2\/media?parent=4425"}],"wp:term":[{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/karklessodyba.lt\/en\/wp-json\/wp\/v2\/yst_prominent_words?post=4425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}